{"id":5176,"date":"2023-09-11T10:12:53","date_gmt":"2023-09-11T10:12:53","guid":{"rendered":"https:\/\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2.jpg"},"modified":"2023-09-11T10:12:53","modified_gmt":"2023-09-11T10:12:53","slug":"tournaments-2023-2024-2","status":"inherit","type":"attachment","link":"https:\/\/www.fsl.lu\/index.php\/2023\/08\/30\/tournois-2023-2024\/tournaments-2023-2024-2\/","title":{"rendered":"Tournaments-2023-2024-2"},"author":3,"comment_status":"open","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"spay_email":""},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a9222d-1lu","jetpack_likes_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/i0.wp.com\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg?ssl=1'><img width=\"300\" height=\"213\" src=\"https:\/\/i0.wp.com\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg?fit=300%2C213&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/i0.wp.com\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg?w=2560&amp;ssl=1 2560w, https:\/\/i0.wp.com\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg?resize=300%2C213&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg?resize=1024%2C727&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg?resize=768%2C545&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg?resize=1536%2C1091&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg?resize=2048%2C1455&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg?w=1800&amp;ssl=1 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-attachment-id=\"5176\" data-permalink=\"https:\/\/www.fsl.lu\/index.php\/2023\/08\/30\/tournois-2023-2024\/tournaments-2023-2024-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg?fit=2560%2C1818&amp;ssl=1\" data-orig-size=\"2560,1818\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tournaments-2023-2024-2\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg?fit=300%2C213&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg?fit=900%2C639&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1818,"file":"2023\/08\/Tournaments-2023-2024-2-scaled.jpg","sizes":{"medium":{"file":"Tournaments-2023-2024-2-300x213.jpg","width":300,"height":213,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg?fit=300%2C213&ssl=1"},"large":{"file":"Tournaments-2023-2024-2-1024x727.jpg","width":1024,"height":727,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg?fit=900%2C639&ssl=1"},"thumbnail":{"file":"Tournaments-2023-2024-2-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg?resize=150%2C150&ssl=1"},"medium_large":{"file":"Tournaments-2023-2024-2-768x545.jpg","width":768,"height":545,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg?fit=768%2C545&ssl=1"},"1536x1536":{"file":"Tournaments-2023-2024-2-1536x1091.jpg","width":1536,"height":1091,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg?fit=1536%2C1091&ssl=1"},"2048x2048":{"file":"Tournaments-2023-2024-2-2048x1455.jpg","width":2048,"height":1455,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg?fit=2048%2C1455&ssl=1"},"post-thumbnail":{"file":"Tournaments-2023-2024-2-900x480.jpg","width":900,"height":480,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg?resize=900%2C480&ssl=1"},"treville-slider-image":{"file":"Tournaments-2023-2024-2-2560x640.jpg","width":2560,"height":640,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg?resize=2560%2C640&ssl=1"},"treville-thumbnail-small":{"file":"Tournaments-2023-2024-2-130x100.jpg","width":130,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg?resize=130%2C100&ssl=1"},"treville-thumbnail-medium":{"file":"Tournaments-2023-2024-2-360x200.jpg","width":360,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg?resize=360%2C200&ssl=1"},"treville-thumbnail-large":{"file":"Tournaments-2023-2024-2-450x250.jpg","width":450,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg?resize=450%2C250&ssl=1"},"full":{"file":"Tournaments-2023-2024-2-scaled.jpg?fit=2560%2C1818&ssl=1","width":2560,"height":1818,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg?fit=2560%2C1818&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"Tournaments-2023-2024-2.jpg"},"post":5146,"source_url":"https:\/\/www.fsl.lu\/wp-content\/uploads\/2023\/08\/Tournaments-2023-2024-2-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.fsl.lu\/index.php\/wp-json\/wp\/v2\/media\/5176"}],"collection":[{"href":"https:\/\/www.fsl.lu\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.fsl.lu\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.fsl.lu\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fsl.lu\/index.php\/wp-json\/wp\/v2\/comments?post=5176"}]}}